{"id":5147,"date":"2019-09-27T20:40:46","date_gmt":"2019-09-28T01:40:46","guid":{"rendered":"https:\/\/kyodai.com.pe\/market\/?post_type=product&#038;p=5147"},"modified":"2026-04-20T06:36:05","modified_gmt":"2026-04-20T11:36:05","slug":"myk-calrose-rice-1-kg","status":"publish","type":"product","link":"https:\/\/kyodai.com.pe\/market\/producto\/myk-calrose-rice-1-kg\/","title":{"rendered":"MYK Arroz Calrose 1 Kg"},"content":{"rendered":"<p>Arroz japon\u00e9s para makis.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Arroz japon\u00e9s para makis.<\/p>\n","protected":false},"author":2,"featured_media":17546,"comment_status":"open","ping_status":"closed","template":"","meta":{"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":""},"product_cat":[71],"product_tag":[],"giftcard-category":[],"aioseo_notices":[],"jetpack_sharing_enabled":true,"featured_img":"https:\/\/kyodai.com.pe\/market\/wp-content\/uploads\/2019\/09\/0320802004.jpg","coauthors":[],"author_meta":{"author_link":"https:\/\/kyodai.com.pe\/market\/author\/market\/","display_name":"Market Kyodai"},"relative_dates":{"created":"Publicado 7 a\u00f1os hace","modified":"Actualizado 3 semanas hace"},"absolute_dates":{"created":"Publicado el 27\/09\/2019","modified":"Actualizado el 20\/04\/2026"},"absolute_dates_time":{"created":"Publicado el 27\/09\/2019 8:40 pm","modified":"Actualizado el 20\/04\/2026 6:36 am"},"featured_img_caption":"","tax_additional":{"product_type":{"linked":["<a href=\"https:\/\/kyodai.com.pe\/market\/?taxonomy=product_type&#038;term=simple\" class=\"advgb-post-tax-term\">simple<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">simple<\/span>"],"slug":"product_type","name":"Tipo de producto"},"product_visibility":{"linked":[],"unlinked":[],"slug":"product_visibility","name":"Visibilidad del producto"},"product_cat":{"linked":["<a href=\"https:\/\/kyodai.com.pe\/market\/categoria-producto\/insumos-orientales\/\" class=\"advgb-post-tax-term\">INSUMOS ORIENTALES<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">INSUMOS ORIENTALES<\/span>"],"slug":"product_cat","name":"Categor\u00edas del producto"},"product_tag":{"linked":[],"unlinked":[],"slug":"product_tag","name":"Etiquetas del producto"},"product_shipping_class":{"linked":[],"unlinked":[],"slug":"product_shipping_class","name":"Clases de env\u00edo del producto"},"pa_color_ropa":{"linked":[],"unlinked":[],"slug":"pa_color_ropa","name":"Color del producto"},"pa_grosor-de-la-pasta":{"linked":[],"unlinked":[],"slug":"pa_grosor-de-la-pasta","name":"Grosor de la pasta del producto"},"pa_modelo":{"linked":[],"unlinked":[],"slug":"pa_modelo","name":"Modelo del producto"},"pa_sabor":{"linked":[],"unlinked":[],"slug":"pa_sabor","name":"Sabor del producto"},"pa_talla_ropa":{"linked":[],"unlinked":[],"slug":"pa_talla_ropa","name":"Talla del producto"},"giftcard-category":{"linked":[],"unlinked":[],"slug":"giftcard-category","name":"Categor\u00edas de la tarjeta regalo"}},"series_order":"","_links":{"self":[{"href":"https:\/\/kyodai.com.pe\/market\/wp-json\/wp\/v2\/product\/5147"}],"collection":[{"href":"https:\/\/kyodai.com.pe\/market\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/kyodai.com.pe\/market\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/kyodai.com.pe\/market\/wp-json\/wp\/v2\/comments?post=5147"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kyodai.com.pe\/market\/wp-json\/wp\/v2\/media\/17546"}],"wp:attachment":[{"href":"https:\/\/kyodai.com.pe\/market\/wp-json\/wp\/v2\/media?parent=5147"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/kyodai.com.pe\/market\/wp-json\/wp\/v2\/product_cat?post=5147"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/kyodai.com.pe\/market\/wp-json\/wp\/v2\/product_tag?post=5147"},{"taxonomy":"giftcard-category","embeddable":true,"href":"https:\/\/kyodai.com.pe\/market\/wp-json\/wp\/v2\/giftcard-category?post=5147"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}