{"id":51406,"date":"2024-08-28T18:10:53","date_gmt":"2024-08-28T23:10:53","guid":{"rendered":"https:\/\/kyodai.com.pe\/market\/?post_type=product&#038;p=51406"},"modified":"2024-08-28T18:10:54","modified_gmt":"2024-08-28T23:10:54","slug":"molde-de-galleta-hello-kitty","status":"publish","type":"product","link":"https:\/\/kyodai.com.pe\/market\/producto\/molde-de-galleta-hello-kitty\/","title":{"rendered":"Molde de galleta Hello Kitty"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":279,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":""},"product_cat":[76,104],"product_tag":[],"giftcard-category":[],"aioseo_notices":[],"jetpack_sharing_enabled":true,"featured_img":false,"coauthors":[],"author_meta":{"author_link":"https:\/\/kyodai.com.pe\/market\/author\/asesor01\/","display_name":"Asesor1 Market"},"relative_dates":{"created":"Publicado 2 a\u00f1os hace","modified":"Actualizado 2 a\u00f1os hace"},"absolute_dates":{"created":"Publicado el 28\/08\/2024","modified":"Actualizado el 28\/08\/2024"},"absolute_dates_time":{"created":"Publicado el 28\/08\/2024 6:10 pm","modified":"Actualizado el 28\/08\/2024 6:10 pm"},"featured_img_caption":"","tax_additional":{"product_type":{"linked":["<a href=\"https:\/\/kyodai.com.pe\/market\/?taxonomy=product_type&#038;term=simple\" class=\"advgb-post-tax-term\">simple<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">simple<\/span>"],"slug":"product_type","name":"Tipo de producto"},"product_visibility":{"linked":[],"unlinked":[],"slug":"product_visibility","name":"Visibilidad del producto"},"product_cat":{"linked":["<a href=\"https:\/\/kyodai.com.pe\/market\/categoria-producto\/hogar-deco\/\" class=\"advgb-post-tax-term\">HOGAR &amp; DECO<\/a>","<a href=\"https:\/\/kyodai.com.pe\/market\/categoria-producto\/hogar-deco\/utensilios-de-cocina\/\" class=\"advgb-post-tax-term\">UTENSILIOS DE COCINA<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">HOGAR &amp; DECO<\/span>","<span class=\"advgb-post-tax-term\">UTENSILIOS DE COCINA<\/span>"],"slug":"product_cat","name":"Categor\u00edas del producto"},"product_tag":{"linked":[],"unlinked":[],"slug":"product_tag","name":"Etiquetas del producto"},"product_shipping_class":{"linked":[],"unlinked":[],"slug":"product_shipping_class","name":"Clases de env\u00edo del producto"},"pa_color_ropa":{"linked":[],"unlinked":[],"slug":"pa_color_ropa","name":"Color del producto"},"pa_grosor-de-la-pasta":{"linked":[],"unlinked":[],"slug":"pa_grosor-de-la-pasta","name":"Grosor de la pasta del producto"},"pa_modelo":{"linked":[],"unlinked":[],"slug":"pa_modelo","name":"Modelo del producto"},"pa_sabor":{"linked":[],"unlinked":[],"slug":"pa_sabor","name":"Sabor del producto"},"pa_talla_ropa":{"linked":[],"unlinked":[],"slug":"pa_talla_ropa","name":"Talla del producto"},"giftcard-category":{"linked":[],"unlinked":[],"slug":"giftcard-category","name":"Categor\u00edas de la tarjeta regalo"}},"series_order":"","_links":{"self":[{"href":"https:\/\/kyodai.com.pe\/market\/wp-json\/wp\/v2\/product\/51406"}],"collection":[{"href":"https:\/\/kyodai.com.pe\/market\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/kyodai.com.pe\/market\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/kyodai.com.pe\/market\/wp-json\/wp\/v2\/comments?post=51406"}],"wp:attachment":[{"href":"https:\/\/kyodai.com.pe\/market\/wp-json\/wp\/v2\/media?parent=51406"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/kyodai.com.pe\/market\/wp-json\/wp\/v2\/product_cat?post=51406"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/kyodai.com.pe\/market\/wp-json\/wp\/v2\/product_tag?post=51406"},{"taxonomy":"giftcard-category","embeddable":true,"href":"https:\/\/kyodai.com.pe\/market\/wp-json\/wp\/v2\/giftcard-category?post=51406"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}