{"id":47662,"date":"2024-02-09T16:20:14","date_gmt":"2024-02-09T21:20:14","guid":{"rendered":"https:\/\/kyodai.com.pe\/market\/?post_type=product&#038;p=47662"},"modified":"2026-09-01T17:08:54","modified_gmt":"2026-09-01T22:08:54","slug":"fruta-mixta-san-jorge-x-55g","status":"publish","type":"product","link":"https:\/\/kyodai.com.pe\/market\/producto\/fruta-mixta-san-jorge-x-55g\/","title":{"rendered":"Galleta SAN JORGE Fruta Mixta 55 gr"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":279,"featured_media":47967,"comment_status":"open","ping_status":"closed","template":"","meta":{"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":""},"product_cat":[70],"product_tag":[],"giftcard-category":[],"aioseo_notices":[],"jetpack_sharing_enabled":true,"featured_img":"https:\/\/kyodai.com.pe\/market\/wp-content\/uploads\/2024\/02\/fruta-mixta.png","coauthors":[],"author_meta":{"author_link":"https:\/\/kyodai.com.pe\/market\/author\/asesor01\/","display_name":"Asesor1 Market"},"relative_dates":{"created":"Publicado 3 a\u00f1os hace","modified":"Actualizado 22 horas hace"},"absolute_dates":{"created":"Publicado el 09\/02\/2024","modified":"Actualizado el 01\/09\/2026"},"absolute_dates_time":{"created":"Publicado el 09\/02\/2024 4:20 pm","modified":"Actualizado el 01\/09\/2026 5:08 pm"},"featured_img_caption":"","tax_additional":{"product_type":{"linked":["<a href=\"https:\/\/kyodai.com.pe\/market\/?taxonomy=product_type&#038;term=simple\" class=\"advgb-post-tax-term\">simple<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">simple<\/span>"],"slug":"product_type","name":"Tipo de producto"},"product_visibility":{"linked":[],"unlinked":[],"slug":"product_visibility","name":"Visibilidad del producto"},"product_cat":{"linked":["<a href=\"https:\/\/kyodai.com.pe\/market\/categoria-producto\/dulces-y-golosinas\/\" class=\"advgb-post-tax-term\">DULCES Y GOLOSINAS<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">DULCES Y GOLOSINAS<\/span>"],"slug":"product_cat","name":"Categor\u00edas del producto"},"product_tag":{"linked":[],"unlinked":[],"slug":"product_tag","name":"Etiquetas del producto"},"product_shipping_class":{"linked":[],"unlinked":[],"slug":"product_shipping_class","name":"Clases de env\u00edo del producto"},"pa_color_ropa":{"linked":[],"unlinked":[],"slug":"pa_color_ropa","name":"Color del producto"},"pa_grosor-de-la-pasta":{"linked":[],"unlinked":[],"slug":"pa_grosor-de-la-pasta","name":"Grosor de la pasta del producto"},"pa_modelo":{"linked":[],"unlinked":[],"slug":"pa_modelo","name":"Modelo del producto"},"pa_sabor":{"linked":[],"unlinked":[],"slug":"pa_sabor","name":"Sabor del producto"},"pa_talla_ropa":{"linked":[],"unlinked":[],"slug":"pa_talla_ropa","name":"Talla del producto"},"giftcard-category":{"linked":[],"unlinked":[],"slug":"giftcard-category","name":"Categor\u00edas de la tarjeta regalo"}},"series_order":"","_links":{"self":[{"href":"https:\/\/kyodai.com.pe\/market\/wp-json\/wp\/v2\/product\/47662"}],"collection":[{"href":"https:\/\/kyodai.com.pe\/market\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/kyodai.com.pe\/market\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/kyodai.com.pe\/market\/wp-json\/wp\/v2\/comments?post=47662"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kyodai.com.pe\/market\/wp-json\/wp\/v2\/media\/47967"}],"wp:attachment":[{"href":"https:\/\/kyodai.com.pe\/market\/wp-json\/wp\/v2\/media?parent=47662"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/kyodai.com.pe\/market\/wp-json\/wp\/v2\/product_cat?post=47662"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/kyodai.com.pe\/market\/wp-json\/wp\/v2\/product_tag?post=47662"},{"taxonomy":"giftcard-category","embeddable":true,"href":"https:\/\/kyodai.com.pe\/market\/wp-json\/wp\/v2\/giftcard-category?post=47662"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}