{"id":31367,"date":"2022-12-26T18:42:36","date_gmt":"2022-12-26T23:42:36","guid":{"rendered":"https:\/\/kyodai.com.pe\/market\/producto\/plantilla\/"},"modified":"2023-12-30T15:34:36","modified_gmt":"2023-12-30T20:34:36","slug":"plantilla","status":"publish","type":"product","link":"https:\/\/kyodai.com.pe\/market\/producto\/plantilla\/","title":{"rendered":"PLANTILLA"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":20,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":""},"product_cat":[166],"product_tag":[],"giftcard-category":[],"aioseo_notices":[],"jetpack_sharing_enabled":true,"featured_img":false,"coauthors":[],"author_meta":{"author_link":"https:\/\/kyodai.com.pe\/market\/author\/paulo-hiyagon\/","display_name":"paulo.hiyagon"},"relative_dates":{"created":"Publicado 3 a\u00f1os hace","modified":"Actualizado 2 a\u00f1os hace"},"absolute_dates":{"created":"Publicado el 26\/12\/2022","modified":"Actualizado el 30\/12\/2023"},"absolute_dates_time":{"created":"Publicado el 26\/12\/2022 6:42 pm","modified":"Actualizado el 30\/12\/2023 3:34 pm"},"featured_img_caption":"","tax_additional":{"product_type":{"linked":["<a href=\"https:\/\/kyodai.com.pe\/market\/?taxonomy=product_type&#038;term=simple\" class=\"advgb-post-tax-term\">simple<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">simple<\/span>"],"slug":"product_type","name":"Tipo de producto"},"product_visibility":{"linked":[],"unlinked":[],"slug":"product_visibility","name":"Visibilidad del producto"},"product_cat":{"linked":["<a href=\"https:\/\/kyodai.com.pe\/market\/categoria-producto\/cuidado-personal\/salud-y-belleza\/\" class=\"advgb-post-tax-term\">SALUD Y BELLEZA<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">SALUD Y BELLEZA<\/span>"],"slug":"product_cat","name":"Categor\u00edas del producto"},"product_tag":{"linked":[],"unlinked":[],"slug":"product_tag","name":"Etiquetas del producto"},"product_shipping_class":{"linked":[],"unlinked":[],"slug":"product_shipping_class","name":"Clases de env\u00edo del producto"},"pa_color_ropa":{"linked":[],"unlinked":[],"slug":"pa_color_ropa","name":"Color del producto"},"pa_grosor-de-la-pasta":{"linked":[],"unlinked":[],"slug":"pa_grosor-de-la-pasta","name":"Grosor de la pasta del producto"},"pa_modelo":{"linked":[],"unlinked":[],"slug":"pa_modelo","name":"Modelo del producto"},"pa_sabor":{"linked":[],"unlinked":[],"slug":"pa_sabor","name":"Sabor del producto"},"pa_talla_ropa":{"linked":[],"unlinked":[],"slug":"pa_talla_ropa","name":"Talla del producto"},"giftcard-category":{"linked":[],"unlinked":[],"slug":"giftcard-category","name":"Categor\u00edas de la tarjeta regalo"}},"series_order":"","_links":{"self":[{"href":"https:\/\/kyodai.com.pe\/market\/wp-json\/wp\/v2\/product\/31367"}],"collection":[{"href":"https:\/\/kyodai.com.pe\/market\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/kyodai.com.pe\/market\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/kyodai.com.pe\/market\/wp-json\/wp\/v2\/comments?post=31367"}],"wp:attachment":[{"href":"https:\/\/kyodai.com.pe\/market\/wp-json\/wp\/v2\/media?parent=31367"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/kyodai.com.pe\/market\/wp-json\/wp\/v2\/product_cat?post=31367"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/kyodai.com.pe\/market\/wp-json\/wp\/v2\/product_tag?post=31367"},{"taxonomy":"giftcard-category","embeddable":true,"href":"https:\/\/kyodai.com.pe\/market\/wp-json\/wp\/v2\/giftcard-category?post=31367"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}