{"id":21262,"date":"2021-01-13T09:34:56","date_gmt":"2021-01-13T14:34:56","guid":{"rendered":"https:\/\/kyodai.com.pe\/market\/?post_type=product&#038;p=21262"},"modified":"2023-12-30T15:30:01","modified_gmt":"2023-12-30T20:30:01","slug":"salsa-de-soya-clara-superior-p-r-b-x-500-ml","status":"publish","type":"product","link":"https:\/\/kyodai.com.pe\/market\/producto\/salsa-de-soya-clara-superior-p-r-b-x-500-ml\/","title":{"rendered":"Salsa de Soya clara Superior P.R.B x 500 ml"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":279,"featured_media":21479,"comment_status":"open","ping_status":"closed","template":"","meta":{"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":""},"product_cat":[71],"product_tag":[],"giftcard-category":[],"aioseo_notices":[],"jetpack_sharing_enabled":true,"featured_img":"https:\/\/kyodai.com.pe\/market\/wp-content\/uploads\/2021\/01\/6921180820025.jpg","coauthors":[],"author_meta":{"author_link":"https:\/\/kyodai.com.pe\/market\/author\/asesor01\/","display_name":"Asesor1 Market"},"relative_dates":{"created":"Publicado 5 a\u00f1os hace","modified":"Actualizado 2 a\u00f1os hace"},"absolute_dates":{"created":"Publicado el 13\/01\/2021","modified":"Actualizado el 30\/12\/2023"},"absolute_dates_time":{"created":"Publicado el 13\/01\/2021 9:34 am","modified":"Actualizado el 30\/12\/2023 3:30 pm"},"featured_img_caption":"","tax_additional":{"product_type":{"linked":["<a href=\"https:\/\/kyodai.com.pe\/market\/?taxonomy=product_type&#038;term=simple\" class=\"advgb-post-tax-term\">simple<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">simple<\/span>"],"slug":"product_type","name":"Tipo de producto"},"product_visibility":{"linked":["<a href=\"https:\/\/kyodai.com.pe\/market\/?taxonomy=product_visibility&#038;term=exclude-from-catalog\" class=\"advgb-post-tax-term\">exclude-from-catalog<\/a>","<a href=\"https:\/\/kyodai.com.pe\/market\/?taxonomy=product_visibility&#038;term=exclude-from-search\" class=\"advgb-post-tax-term\">exclude-from-search<\/a>","<a href=\"https:\/\/kyodai.com.pe\/market\/?taxonomy=product_visibility&#038;term=outofstock\" class=\"advgb-post-tax-term\">outofstock<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">exclude-from-catalog<\/span>","<span class=\"advgb-post-tax-term\">exclude-from-search<\/span>","<span class=\"advgb-post-tax-term\">outofstock<\/span>"],"slug":"product_visibility","name":"Visibilidad del producto"},"product_cat":{"linked":["<a href=\"https:\/\/kyodai.com.pe\/market\/categoria-producto\/insumos-orientales\/\" class=\"advgb-post-tax-term\">INSUMOS ORIENTALES<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">INSUMOS ORIENTALES<\/span>"],"slug":"product_cat","name":"Categor\u00edas del producto"},"product_tag":{"linked":[],"unlinked":[],"slug":"product_tag","name":"Etiquetas del producto"},"product_shipping_class":{"linked":[],"unlinked":[],"slug":"product_shipping_class","name":"Clases de env\u00edo del producto"},"pa_color_ropa":{"linked":[],"unlinked":[],"slug":"pa_color_ropa","name":"Color del producto"},"pa_grosor-de-la-pasta":{"linked":[],"unlinked":[],"slug":"pa_grosor-de-la-pasta","name":"Grosor de la pasta del producto"},"pa_modelo":{"linked":[],"unlinked":[],"slug":"pa_modelo","name":"Modelo del producto"},"pa_sabor":{"linked":[],"unlinked":[],"slug":"pa_sabor","name":"Sabor del producto"},"pa_talla_ropa":{"linked":[],"unlinked":[],"slug":"pa_talla_ropa","name":"Talla del producto"},"giftcard-category":{"linked":[],"unlinked":[],"slug":"giftcard-category","name":"Categor\u00edas de la tarjeta regalo"}},"series_order":"","_links":{"self":[{"href":"https:\/\/kyodai.com.pe\/market\/wp-json\/wp\/v2\/product\/21262"}],"collection":[{"href":"https:\/\/kyodai.com.pe\/market\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/kyodai.com.pe\/market\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/kyodai.com.pe\/market\/wp-json\/wp\/v2\/comments?post=21262"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kyodai.com.pe\/market\/wp-json\/wp\/v2\/media\/21479"}],"wp:attachment":[{"href":"https:\/\/kyodai.com.pe\/market\/wp-json\/wp\/v2\/media?parent=21262"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/kyodai.com.pe\/market\/wp-json\/wp\/v2\/product_cat?post=21262"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/kyodai.com.pe\/market\/wp-json\/wp\/v2\/product_tag?post=21262"},{"taxonomy":"giftcard-category","embeddable":true,"href":"https:\/\/kyodai.com.pe\/market\/wp-json\/wp\/v2\/giftcard-category?post=21262"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}