{"id":15892,"date":"2020-05-30T22:45:56","date_gmt":"2020-05-31T03:45:56","guid":{"rendered":"https:\/\/kyodai.com.pe\/market\/?post_type=product&#038;p=15892"},"modified":"2024-11-07T10:40:20","modified_gmt":"2024-11-07T15:40:20","slug":"lonchera-acero-inox-2-compar-azul-0-70-lt","status":"publish","type":"product","link":"https:\/\/kyodai.com.pe\/market\/producto\/lonchera-acero-inox-2-compar-azul-0-70-lt\/","title":{"rendered":"Lonchera Acero Inox 2 Compart. (azul) 0.70 Lt. SL-MEE07AB"},"content":{"rendered":"<p>Retenci\u00f3n de calor a 69\u00b0C x 6h. aprox.<br \/>\nContenedor 1 (0.31 lt cap)<br \/>\nContenedor 2 (0.33 lt cap)<br \/>\nViene con Malet\u00edn +\u00a0ohashi c\/estuche<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lonchera Acero Inox 2 compartimientos.<\/p>\n","protected":false},"author":20,"featured_media":15924,"comment_status":"open","ping_status":"closed","template":"","meta":{"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":""},"product_cat":[63],"product_tag":[],"giftcard-category":[],"aioseo_notices":[],"jetpack_sharing_enabled":true,"featured_img":"https:\/\/kyodai.com.pe\/market\/wp-content\/uploads\/2020\/05\/4974305707413.jpg","coauthors":[],"author_meta":{"author_link":"https:\/\/kyodai.com.pe\/market\/author\/paulo-hiyagon\/","display_name":"paulo.hiyagon"},"relative_dates":{"created":"Publicado 6 a\u00f1os hace","modified":"Actualizado 2 a\u00f1os hace"},"absolute_dates":{"created":"Publicado el 30\/05\/2020","modified":"Actualizado el 07\/11\/2024"},"absolute_dates_time":{"created":"Publicado el 30\/05\/2020 10:45 pm","modified":"Actualizado el 07\/11\/2024 10:40 am"},"featured_img_caption":"","tax_additional":{"product_type":{"linked":["<a href=\"https:\/\/kyodai.com.pe\/market\/?taxonomy=product_type&#038;term=simple\" class=\"advgb-post-tax-term\">simple<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">simple<\/span>"],"slug":"product_type","name":"Tipo de producto"},"product_visibility":{"linked":["<a href=\"https:\/\/kyodai.com.pe\/market\/?taxonomy=product_visibility&#038;term=outofstock\" class=\"advgb-post-tax-term\">outofstock<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">outofstock<\/span>"],"slug":"product_visibility","name":"Visibilidad del producto"},"product_cat":{"linked":["<a href=\"https:\/\/kyodai.com.pe\/market\/categoria-producto\/zojirushi\/loncheras\/\" class=\"advgb-post-tax-term\">LONCHERAS<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">LONCHERAS<\/span>"],"slug":"product_cat","name":"Categor\u00edas del producto"},"product_tag":{"linked":[],"unlinked":[],"slug":"product_tag","name":"Etiquetas del producto"},"product_shipping_class":{"linked":[],"unlinked":[],"slug":"product_shipping_class","name":"Clases de env\u00edo del producto"},"pa_color_ropa":{"linked":[],"unlinked":[],"slug":"pa_color_ropa","name":"Color del producto"},"pa_grosor-de-la-pasta":{"linked":[],"unlinked":[],"slug":"pa_grosor-de-la-pasta","name":"Grosor de la pasta del producto"},"pa_modelo":{"linked":[],"unlinked":[],"slug":"pa_modelo","name":"Modelo del producto"},"pa_sabor":{"linked":[],"unlinked":[],"slug":"pa_sabor","name":"Sabor del producto"},"pa_talla_ropa":{"linked":[],"unlinked":[],"slug":"pa_talla_ropa","name":"Talla del producto"},"giftcard-category":{"linked":[],"unlinked":[],"slug":"giftcard-category","name":"Categor\u00edas de la tarjeta regalo"}},"series_order":"","_links":{"self":[{"href":"https:\/\/kyodai.com.pe\/market\/wp-json\/wp\/v2\/product\/15892"}],"collection":[{"href":"https:\/\/kyodai.com.pe\/market\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/kyodai.com.pe\/market\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/kyodai.com.pe\/market\/wp-json\/wp\/v2\/comments?post=15892"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kyodai.com.pe\/market\/wp-json\/wp\/v2\/media\/15924"}],"wp:attachment":[{"href":"https:\/\/kyodai.com.pe\/market\/wp-json\/wp\/v2\/media?parent=15892"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/kyodai.com.pe\/market\/wp-json\/wp\/v2\/product_cat?post=15892"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/kyodai.com.pe\/market\/wp-json\/wp\/v2\/product_tag?post=15892"},{"taxonomy":"giftcard-category","embeddable":true,"href":"https:\/\/kyodai.com.pe\/market\/wp-json\/wp\/v2\/giftcard-category?post=15892"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}