{"id":15860,"date":"2020-05-30T17:31:37","date_gmt":"2020-05-30T22:31:37","guid":{"rendered":"https:\/\/kyodai.com.pe\/market\/producto\/kuru-helado-de-lucuma\/"},"modified":"2023-12-30T15:28:17","modified_gmt":"2023-12-30T20:28:17","slug":"kuru-helado-de-lucuma","status":"publish","type":"product","link":"https:\/\/kyodai.com.pe\/market\/producto\/kuru-helado-de-lucuma\/","title":{"rendered":"KURU KURU Helado de L\u00facuma"},"content":{"rendered":"<p>Helado de L\u00facuma<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Helado de L\u00facuma<\/p>\n","protected":false},"author":20,"featured_media":16138,"comment_status":"open","ping_status":"closed","template":"","meta":{"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":""},"product_cat":[82],"product_tag":[],"giftcard-category":[],"aioseo_notices":[],"jetpack_sharing_enabled":true,"featured_img":"https:\/\/kyodai.com.pe\/market\/wp-content\/uploads\/2020\/06\/C003.jpg","coauthors":[],"author_meta":{"author_link":"https:\/\/kyodai.com.pe\/market\/author\/paulo-hiyagon\/","display_name":"paulo.hiyagon"},"relative_dates":{"created":"Publicado 6 a\u00f1os hace","modified":"Actualizado 2 a\u00f1os hace"},"absolute_dates":{"created":"Publicado el 30\/05\/2020","modified":"Actualizado el 30\/12\/2023"},"absolute_dates_time":{"created":"Publicado el 30\/05\/2020 5:31 pm","modified":"Actualizado el 30\/12\/2023 3:28 pm"},"featured_img_caption":"","tax_additional":{"product_type":{"linked":["<a href=\"https:\/\/kyodai.com.pe\/market\/?taxonomy=product_type&#038;term=simple\" class=\"advgb-post-tax-term\">simple<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">simple<\/span>"],"slug":"product_type","name":"Tipo de producto"},"product_visibility":{"linked":["<a href=\"https:\/\/kyodai.com.pe\/market\/?taxonomy=product_visibility&#038;term=outofstock\" class=\"advgb-post-tax-term\">outofstock<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">outofstock<\/span>"],"slug":"product_visibility","name":"Visibilidad del producto"},"product_cat":{"linked":["<a href=\"https:\/\/kyodai.com.pe\/market\/categoria-producto\/helados\/\" class=\"advgb-post-tax-term\">HELADOS<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">HELADOS<\/span>"],"slug":"product_cat","name":"Categor\u00edas del producto"},"product_tag":{"linked":[],"unlinked":[],"slug":"product_tag","name":"Etiquetas del producto"},"product_shipping_class":{"linked":[],"unlinked":[],"slug":"product_shipping_class","name":"Clases de env\u00edo del producto"},"pa_color_ropa":{"linked":[],"unlinked":[],"slug":"pa_color_ropa","name":"Color del producto"},"pa_grosor-de-la-pasta":{"linked":[],"unlinked":[],"slug":"pa_grosor-de-la-pasta","name":"Grosor de la pasta del producto"},"pa_modelo":{"linked":[],"unlinked":[],"slug":"pa_modelo","name":"Modelo del producto"},"pa_sabor":{"linked":[],"unlinked":[],"slug":"pa_sabor","name":"Sabor del producto"},"pa_talla_ropa":{"linked":[],"unlinked":[],"slug":"pa_talla_ropa","name":"Talla del producto"},"giftcard-category":{"linked":[],"unlinked":[],"slug":"giftcard-category","name":"Categor\u00edas de la tarjeta regalo"}},"series_order":"","_links":{"self":[{"href":"https:\/\/kyodai.com.pe\/market\/wp-json\/wp\/v2\/product\/15860"}],"collection":[{"href":"https:\/\/kyodai.com.pe\/market\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/kyodai.com.pe\/market\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/kyodai.com.pe\/market\/wp-json\/wp\/v2\/comments?post=15860"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kyodai.com.pe\/market\/wp-json\/wp\/v2\/media\/16138"}],"wp:attachment":[{"href":"https:\/\/kyodai.com.pe\/market\/wp-json\/wp\/v2\/media?parent=15860"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/kyodai.com.pe\/market\/wp-json\/wp\/v2\/product_cat?post=15860"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/kyodai.com.pe\/market\/wp-json\/wp\/v2\/product_tag?post=15860"},{"taxonomy":"giftcard-category","embeddable":true,"href":"https:\/\/kyodai.com.pe\/market\/wp-json\/wp\/v2\/giftcard-category?post=15860"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}